{"id":12457,"date":"2017-01-11T19:20:16","date_gmt":"2017-01-11T18:20:16","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=12457"},"modified":"2017-01-11T19:29:56","modified_gmt":"2017-01-11T18:29:56","slug":"un-roi-et-deux-reines","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2017\/01\/11\/un-roi-et-deux-reines\/","title":{"rendered":"un Roi et deux Reines"},"content":{"rendered":"<p>En ce mercredi d&rsquo;entrainement, l&rsquo;\u00e9cole d&rsquo;escrime de la Section Paloise a tir\u00e9 les rois dans une ambiance chaleureuse et d\u00e9contract\u00e9e. Alexia et Constance sont devenues Reines d&rsquo;un jour et le Roi s&rsquo;appelle Marius. Et ce weekend place \u00e0 la comp\u00e9tition avec le circuit inter-r\u00e9gional organis\u00e9 par le Cam Bordeaux. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>En ce mercredi d&rsquo;entrainement, l&rsquo;\u00e9cole d&rsquo;escrime de la Section Paloise a tir\u00e9 les rois dans une ambiance chaleureuse et d\u00e9contract\u00e9e. Alexia et Constance sont devenues Reines d&rsquo;un jour et le Roi s&rsquo;appelle Marius. Et ce weekend place \u00e0 la comp\u00e9tition avec le circuit inter-r\u00e9gional organis\u00e9 par le Cam Bordeaux.<\/p>\n","protected":false},"author":6,"featured_media":12458,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=12457"}],"version-history":[{"count":1,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12457\/revisions"}],"predecessor-version":[{"id":12459,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12457\/revisions\/12459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/12458"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=12457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=12457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=12457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}