{"id":12646,"date":"2017-05-09T22:09:45","date_gmt":"2017-05-09T20:09:45","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=12646"},"modified":"2017-05-11T15:54:40","modified_gmt":"2017-05-11T13:54:40","slug":"les-paloises-en-bronze","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2017\/05\/09\/les-paloises-en-bronze\/","title":{"rendered":"Les paloises en bronze."},"content":{"rendered":"<p>On \u00e9tait habitu\u00e9 depuis 6 ans \u00e0 ceux que les gar\u00e7ons de la section trustent les titres aux championnats de France seniors  \u00c9lite, cest autour des filles de cr\u00e9er le buzz en obtenant une m\u00e9daille de bronze synonyme de cons\u00e9cration pour tout le staff palois. F\u00e9licitations \u00e0 nos 4 super bretteuses : Sandra Marcos, jeromine Massou, Marie Delas Et Julie Saint Cricq qui ont \u00e9limin\u00e9 les \u00e9quipes de l usmetro Et Roubaix et leurs pl\u00e9iades d internationales. Chez les hommes, apr\u00e8s les retraites internationales de Julien Medard Et Fernando Casares, la t\u00e2che s&rsquo;annon\u00e7ait difficile. Les palois \u00e9chouent en quart sur Gisors Et assurent le maintien en battant Meylan 45 \u00e0 39. En individuel, Eliott Bibi tout juste 17 ans perd en quart sur Vincent Anstett quart de finaliste aux jeux de Rio. Enfin en troisi\u00e8me division, pierre Saint Cricq encore cadet devient champion de France tandis que sam Jarry lui aussi cadet finit 3. Rendez vous le week end prochain \u00e0 Dunkerque pour les championnats de France cadets.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>On \u00e9tait habitu\u00e9 depuis 6 ans \u00e0 ceux que les gar\u00e7ons de la section trustent les titres aux championnats de France seniors \u00c9lite, cest autour des filles de cr\u00e9er le buzz en obtenant une m\u00e9daille de bronze synonyme de cons\u00e9cration pour tout le staff palois. F\u00e9licitations \u00e0 nos 4 super bretteuses : Sandra Marcos, jeromine [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12647,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=12646"}],"version-history":[{"count":2,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12646\/revisions"}],"predecessor-version":[{"id":12654,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12646\/revisions\/12654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/12647"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=12646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=12646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=12646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}