{"id":12743,"date":"2017-06-13T14:43:25","date_gmt":"2017-06-13T12:43:25","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=12743"},"modified":"2017-06-13T14:43:25","modified_gmt":"2017-06-13T12:43:25","slug":"de-la-section-paloise-a-san-diego","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2017\/06\/13\/de-la-section-paloise-a-san-diego\/","title":{"rendered":"De la Section Paloise \u00e0 San Diego"},"content":{"rendered":"<p>Quelle joie et quel honneur de retrouver Andr\u00e9 Tran, un ancien sectionniste, qui a commenc\u00e9 l&rsquo;escrime il y a plus de 45 ans  au stadium de la gare avec ses 2 fr\u00e8res Emile et Antoine. Venu \u00e0 l&rsquo;escrime gr\u00e2ce \u00e0 Pierre Coicaud qui avait alors d\u00e9cel\u00e9 un vrai potentiel chez ces 3 gar\u00e7ons, Andr\u00e9 est actuellement docteur \u00e0 l&rsquo;universit\u00e9 Harvard de San Diego et continue \u00e0 manier le sabre \u00e0 ces heures perdues. Que de souvenirs et quelle joie de retrouver notre fr\u00e8re d&rsquo;armes, les autres bretteurs de l&rsquo;\u00e9poque \u00e9tant les fr\u00e8res Casabonne (Pascal et Fran\u00e7ois) et Gaby (Bruno, Pierre-Jean et Thierry). Andr\u00e9 \u00e9tait la semaine derni\u00e8re en visite en France pour montrer et partager avec son fils les lieux et les personnes qui ont marqu\u00e9s sa jeunesse.  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quelle joie et quel honneur de retrouver Andr\u00e9 Tran, un ancien sectionniste, qui a commenc\u00e9 l&rsquo;escrime il y a plus de 45 ans au stadium de la gare avec ses 2 fr\u00e8res Emile et Antoine. Venu \u00e0 l&rsquo;escrime gr\u00e2ce \u00e0 Pierre Coicaud qui avait alors d\u00e9cel\u00e9 un vrai potentiel chez ces 3 gar\u00e7ons, Andr\u00e9 est [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12744,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=12743"}],"version-history":[{"count":1,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12743\/revisions"}],"predecessor-version":[{"id":12745,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/12743\/revisions\/12745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/12744"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=12743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=12743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=12743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}