{"id":13345,"date":"2018-10-08T19:00:11","date_gmt":"2018-10-08T17:00:11","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=13345"},"modified":"2018-10-08T19:58:06","modified_gmt":"2018-10-08T17:58:06","slug":"pierre-blasco-en-bronze","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2018\/10\/08\/pierre-blasco-en-bronze\/","title":{"rendered":"Pierre Blasco en bronze"},"content":{"rendered":"<div id=\"yiv5849129235yui_3_16_0_ym19_1_1539010698932_8469\">Ce week-end avait lieu \u00e0 G\u00e9m\u00e9nos dans la banlieue de Marseille\u00a0deux circuits nationaux \u00ab\u00a0\u00e9lite\u00a0\u00bb\u00a0cadets et s\u00e9niors. La section paloise escrime alignait \u00a017 comp\u00e9titeurs et\u00a0la meilleure performance est \u00e0 mettre au cr\u00e9dit de Pierre Blasco qui monte sur la troisi\u00e8me marche du podium en cadet. Pierre a domin\u00e9 ais\u00e9ment tous ses adversaires notamment deux des favoris\u00a0le parisien Martin Courbe 15 \u00e0 8 et le breton Maruelle 15 \u00e0 10 avant d&rsquo;\u00e9chouer sur le bigourdan Sans\u00a0en demi finale 15 \u00e0 12. En s\u00e9niors, J\u00e9romine Massou termine 5\u00e8me, battue par la marseillaise Poupinet 15 \u00e0 13. J\u00e9romine\u00a0\u00a0qui fait actuellement ses \u00e9tudes \u00e0 Madrid et qui s&rsquo;entra\u00eene avec l&rsquo;\u00e9quipe d&rsquo;Espagne a incontestablement gagn\u00e9 en confiance et\u00a0 peut regretter 2 ou 3 d\u00e9cisions arbitrales d\u00e9favorables.<\/div>\n<div id=\"yiv5849129235yui_3_16_0_ym19_1_1539010698932_8406\" dir=\"ltr\">En s\u00e9niors gar\u00e7ons, \u00e0 noter l&rsquo;excellente performance de Paco Boureau \u00e0 peine 18 ans\u00a0qui finit 13\u00e8me en \u00e9liminant notamment l&rsquo;exp\u00e9riment\u00e9 tunisien Hicham Samandi 48\u00e8me mondial. En cadette enfin, Roxane cayrat encore minime \u00e9limine la parisienne Lisa Chen, championne de France en titre et se classe \u00e0 une tr\u00e8s bonne 15\u00e8me place<\/div>\n<div dir=\"ltr\"><a href=\"http:\/\/www.escrime-info.com\/gregxml\/Greg\/afficher.php?fichier=.\/resultats\/SHM17\/CN\/20181007Gemenos Tableau A indiv.xml&amp;mode=Classement\">R\u00e9sultats cadets<\/a><\/div>\n<div dir=\"ltr\"><a href=\"http:\/\/www.escrime-info.com\/gregxml\/Greg\/afficher.php?fichier=.\/resultats\/SDM17\/CN\/20181007Gemenos indiv.xml&amp;mode=Classement\">R\u00e9sultats cadettes<\/a><\/div>\n<div dir=\"ltr\"><a href=\"http:\/\/www.escrime-info.com\/gregxml\/Greg\/afficher.php?fichier=.\/resultats\/SHS\/CN\/20181006Gemenos indiv.xml&amp;mode=Classement\">R\u00e9sultats s\u00e9niors gar\u00e7ons<\/a><\/div>\n<div dir=\"ltr\"><a href=\"http:\/\/www.escrime-info.com\/gregxml\/Greg\/afficher.php?fichier=.\/resultats\/SDS\/CN\/20181006Gemenos indiv.xml&amp;mode=Classement\">R\u00e9sultats s\u00e9niors filles<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ce week-end avait lieu \u00e0 G\u00e9m\u00e9nos dans la banlieue de Marseille\u00a0deux circuits nationaux \u00ab\u00a0\u00e9lite\u00a0\u00bb\u00a0cadets et s\u00e9niors. La section paloise escrime alignait \u00a017 comp\u00e9titeurs et\u00a0la meilleure performance est \u00e0 mettre au cr\u00e9dit de Pierre Blasco qui monte sur la troisi\u00e8me marche du podium en cadet. Pierre a domin\u00e9 ais\u00e9ment tous ses adversaires notamment deux des favoris\u00a0le [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":13346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/13345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=13345"}],"version-history":[{"count":3,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/13345\/revisions"}],"predecessor-version":[{"id":13354,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/13345\/revisions\/13354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/13346"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=13345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=13345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=13345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}