{"id":13483,"date":"2018-11-26T10:15:06","date_gmt":"2018-11-26T09:15:06","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=13483"},"modified":"2018-11-26T10:15:06","modified_gmt":"2018-11-26T09:15:06","slug":"maxime-bellay-vainqueur-a-ornon","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2018\/11\/26\/maxime-bellay-vainqueur-a-ornon\/","title":{"rendered":"Maxime Bellay vainqueur \u00e0 Ornon"},"content":{"rendered":"<p>Tr\u00e8s belle victoire de Maxime Bellay ce week-end \u00e0 Ornon pour le circuit r\u00e9gional \u00e9p\u00e9e s\u00e9niors qui regroupait quelques 44 tireurs. Dominateur toute la journ\u00e9e, Maxime s&rsquo;est notamment impos\u00e9 en demi-finale sur Gu\u00e9nard de Villeneuve sur Lot 15\u00e05 et sur Jouganous d&rsquo;Ornon 15\u00e09. L&rsquo;autre palois engag\u00e9 Julien Diaz perd en 16\u00e8me de finale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00e8s belle victoire de Maxime Bellay ce week-end \u00e0 Ornon pour le circuit r\u00e9gional \u00e9p\u00e9e s\u00e9niors qui regroupait quelques 44 tireurs. Dominateur toute la journ\u00e9e, Maxime s&rsquo;est notamment impos\u00e9 en demi-finale sur Gu\u00e9nard de Villeneuve sur Lot 15\u00e05 et sur Jouganous d&rsquo;Ornon 15\u00e09. L&rsquo;autre palois engag\u00e9 Julien Diaz perd en 16\u00e8me de finale.<\/p>\n","protected":false},"author":6,"featured_media":13484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-13483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/13483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=13483"}],"version-history":[{"count":1,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/13483\/revisions"}],"predecessor-version":[{"id":13485,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/13483\/revisions\/13485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/13484"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=13483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=13483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=13483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}