{"id":14155,"date":"2019-11-27T22:27:20","date_gmt":"2019-11-27T21:27:20","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=14155"},"modified":"2019-11-27T22:27:20","modified_gmt":"2019-11-27T21:27:20","slug":"super-mario-champion-de-colombie","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2019\/11\/27\/super-mario-champion-de-colombie\/","title":{"rendered":"Super Mario Champion de Colombie"},"content":{"rendered":"<p>Nos palois ont brill\u00e9 aux championnats de Colombie avec une magnifique victoire de Mario Palacios et une troisi\u00e8me place de S\u00e9bastian Cuellar, nos deux palois s&rsquo;\u00e9liminant en demi-finale. Bravo Mario pour ton premier titre qui on l&rsquo;esp\u00e8re en appellera d&rsquo;autres.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nos palois ont brill\u00e9 aux championnats de Colombie avec une magnifique victoire de Mario Palacios et une troisi\u00e8me place de S\u00e9bastian Cuellar, nos deux palois s&rsquo;\u00e9liminant en demi-finale. Bravo Mario pour ton premier titre qui on l&rsquo;esp\u00e8re en appellera d&rsquo;autres. &nbsp;<\/p>\n","protected":false},"author":6,"featured_media":14156,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-14155","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/14155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=14155"}],"version-history":[{"count":1,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/14155\/revisions"}],"predecessor-version":[{"id":14158,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/14155\/revisions\/14158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/14156"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=14155"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=14155"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=14155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}