{"id":24585,"date":"2021-11-18T22:11:43","date_gmt":"2021-11-18T21:11:43","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=24585"},"modified":"2021-11-18T22:11:43","modified_gmt":"2021-11-18T21:11:43","slug":"que-de-beau-monde","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2021\/11\/18\/que-de-beau-monde\/","title":{"rendered":"Que de beau monde"},"content":{"rendered":"<p>Cette semaine \u00e9tait pr\u00e9sents \u00e0 la salle d&rsquo;armes nos 3 \u00ab\u00a0Insepiens\u00a0\u00bb Sam, Paco et Eliott, qui cumulent nombre de titres de champions de France. Etaient \u00e9galement dans nos locaux Alejandro et son entra\u00eeneur Cessar, 2 escrimeurs colombiens qui pr\u00e9parent les jeux panam\u00e9ricains de la jeunesse, l&rsquo;occasion pour tous nos licenci\u00e9s de croiser le fer avec tous ces champions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette semaine \u00e9tait pr\u00e9sents \u00e0 la salle d&rsquo;armes nos 3 \u00ab\u00a0Insepiens\u00a0\u00bb Sam, Paco et Eliott, qui cumulent nombre de titres de champions de France. Etaient \u00e9galement dans nos locaux Alejandro et son entra\u00eeneur Cessar, 2 escrimeurs colombiens qui pr\u00e9parent les jeux panam\u00e9ricains de la jeunesse, l&rsquo;occasion pour tous nos licenci\u00e9s de croiser le fer avec [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":24586,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/24585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=24585"}],"version-history":[{"count":1,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/24585\/revisions"}],"predecessor-version":[{"id":24587,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/24585\/revisions\/24587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/24586"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=24585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=24585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=24585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}