{"id":24707,"date":"2022-02-13T13:30:56","date_gmt":"2022-02-13T12:30:56","guid":{"rendered":"http:\/\/www.escrimepaloise.com\/wordpress\/?p=24707"},"modified":"2022-02-13T13:30:56","modified_gmt":"2022-02-13T12:30:56","slug":"guigui-vainqueur-du-championnat-de-ligue-universitaire","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2022\/02\/13\/guigui-vainqueur-du-championnat-de-ligue-universitaire\/","title":{"rendered":"Guigui vainqueur du championnat de ligue Universitaire"},"content":{"rendered":"<p>Guigui vient de gagner le championnat de ligue universitaire sur Pierre sur le score de 15 \u00e0 13, nos 2 sectionnistes assurant leur qualification pour les championnats de France.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Guigui vient de gagner le championnat de ligue universitaire sur Pierre sur le score de 15 \u00e0 13, nos 2 sectionnistes assurant leur qualification pour les championnats de France.<\/p>\n","protected":false},"author":7,"featured_media":24708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-24707","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/02\/IMG_2101.jpg?fit=827%2C930&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8aWQh-6qv","jetpack-related-posts":[{"id":24781,"url":"https:\/\/www.escrimepaloise.com\/wordpress\/2022\/03\/30\/pierre-champion-de-france-universitaire\/","url_meta":{"origin":24707,"position":0},"title":"Pierre champion de France universitaire","author":"Alain","date":"30 mars 2022","format":false,"excerpt":"Premier titre de champion de France 2022 obtenu par la Section Paloise Escrime gr\u00e2ce \u00e0 Pierre Blasco qui domine le tarbais Custine en finale. Guigui termine troisi\u00e8me battu par son camarade de club 15 \u00e0 13. R\u00e9sultats","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.escrimepaloise.com\/wordpress\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/414d2dfd-e538-4e0d-8438-1648a46f3be7-e1648672176617.jpg?fit=800%2C1067&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/414d2dfd-e538-4e0d-8438-1648a46f3be7-e1648672176617.jpg?fit=800%2C1067&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/414d2dfd-e538-4e0d-8438-1648a46f3be7-e1648672176617.jpg?fit=800%2C1067&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/414d2dfd-e538-4e0d-8438-1648a46f3be7-e1648672176617.jpg?fit=800%2C1067&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24773,"url":"https:\/\/www.escrimepaloise.com\/wordpress\/2022\/03\/27\/guigui-et-lequipe-juniors-sur-le-podium\/","url_meta":{"origin":24707,"position":1},"title":"Guigui et l&rsquo;\u00e9quipe Juniors sur le podium","author":"Alain","date":"27 mars 2022","format":false,"excerpt":"Grosse performance de Guigui\u00a0 et de l'\u00e9quipe gar\u00e7ons ce week-end \u00e0 Orl\u00e9ans \u00e0 l'occasion du circuit national juniors. Guigui prend la troisi\u00e8me place en individuel battu 15 \u00e0 14 en demi-finale par un Orl\u00e9annais. Par \u00e9quipe, Ugo, Albin, Nolann et Guigui finissent second battu par une des 3 \u00e9quipes orl\u00e9annaise.\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.escrimepaloise.com\/wordpress\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/26e6e94d-01d6-4ce7-a857-b4db09c44427-e1648406801777.jpg?fit=800%2C450&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/26e6e94d-01d6-4ce7-a857-b4db09c44427-e1648406801777.jpg?fit=800%2C450&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/26e6e94d-01d6-4ce7-a857-b4db09c44427-e1648406801777.jpg?fit=800%2C450&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/03\/26e6e94d-01d6-4ce7-a857-b4db09c44427-e1648406801777.jpg?fit=800%2C450&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":26641,"url":"https:\/\/www.escrimepaloise.com\/wordpress\/2025\/06\/25\/guigui-en-stage-en-arabie-saoudite\/","url_meta":{"origin":24707,"position":2},"title":"Guigui en stage en Arabie Saoudite","author":"Alain","date":"25 juin 2025","format":false,"excerpt":"Guigui a eu la chance d'\u00eatre retenu par Julien M\u00e9dard, entra\u00eeneur national du p\u00f4le rel\u00e8ve de Talence, pour passer un s\u00e9jour en Arabie Saoudite et s'entra\u00eener quotidiennement avec l'\u00e9quipe nationale. Une exp\u00e9rience fort enrichissante.","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.escrimepaloise.com\/wordpress\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2025\/06\/guigui-2.jpg?fit=543%2C405&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2025\/06\/guigui-2.jpg?fit=543%2C405&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2025\/06\/guigui-2.jpg?fit=543%2C405&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":13135,"url":"https:\/\/www.escrimepaloise.com\/wordpress\/2018\/04\/08\/henri-et-guigui-en-champagne-ardennes\/","url_meta":{"origin":24707,"position":3},"title":"Henri et Guigui en Champagne Ardennes","author":"Alain C.","date":"8 avril 2018","format":false,"excerpt":"Un coup de chapeau \u00e0 Henri et Guigui d'avoir travers\u00e9 la France et fait plus de 1000 bornes pour aller disputer une comp\u00e9tition d'escrime. C'est d\u00e9j\u00e0 en soi une performance. Quand on sait que nos 2 sectionnistes terminent huiti\u00e8me et douzi\u00e8me, on ne peut que les f\u00e9liciter d'avoir fait le\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.escrimepaloise.com\/wordpress\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2018\/04\/IMG_3339-e1523221208765.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2018\/04\/IMG_3339-e1523221208765.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2018\/04\/IMG_3339-e1523221208765.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2018\/04\/IMG_3339-e1523221208765.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":24785,"url":"https:\/\/www.escrimepaloise.com\/wordpress\/2022\/04\/03\/grand-chelem-au-championnat-de-ligue\/","url_meta":{"origin":24707,"position":4},"title":"Grand Chelem au championnat de ligue","author":"Alain","date":"3 avril 2022","format":false,"excerpt":"Ce week-end \u00e0 Pessac, la Section \u00e9tait repr\u00e9sent\u00e9e dans 9 \u00e9preuves de jeunes et a gagn\u00e9 les 9 comp\u00e9titions. Bravi \u00e0 Isa\u00e9, Isaure et Laia chez les filles. Bravo \u00e0 Jules, Augustin, Romain et Antoine chez les gar\u00e7ons. Et enfin f\u00e9licitations \u00e0 l'\u00e9quipe benjamin et minime gar\u00e7ons. Les jeunes sont\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.escrimepaloise.com\/wordpress\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/04\/IMG_8739-e1649014638291.jpg?fit=800%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/04\/IMG_8739-e1649014638291.jpg?fit=800%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/04\/IMG_8739-e1649014638291.jpg?fit=800%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2022\/04\/IMG_8739-e1649014638291.jpg?fit=800%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":13707,"url":"https:\/\/www.escrimepaloise.com\/wordpress\/2019\/03\/10\/championnat-de-ligue-au-bouscat\/","url_meta":{"origin":24707,"position":5},"title":"Championnat de Ligue au Bouscat","author":"Alain C.","date":"10 mars 2019","format":false,"excerpt":"Ce week-end avait lieu au Bouscat le championnat de ligue au sabre de la cat\u00e9gorie M11 \u00e0 S\u00e9niors. La Section Paloise a obtenu 8 titres gr\u00e2ce \u00e0 La\u00efa Bergez en M13, Albin Guyonnaud en M15, Pierre Blasco et Garance Baylaucq en M17, Samuel Jarry en s\u00e9niors, l'\u00e9quipe minime compos\u00e9e d'Albin\u2026","rel":"","context":"Dans &quot;Non class\u00e9&quot;","block_context":{"text":"Non class\u00e9","link":"https:\/\/www.escrimepaloise.com\/wordpress\/category\/non-classe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2019\/03\/Les-grands-e1552247159932.jpg?fit=800%2C463&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2019\/03\/Les-grands-e1552247159932.jpg?fit=800%2C463&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2019\/03\/Les-grands-e1552247159932.jpg?fit=800%2C463&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/www.escrimepaloise.com\/wordpress\/wp-content\/uploads\/2019\/03\/Les-grands-e1552247159932.jpg?fit=800%2C463&ssl=1&resize=700%2C400 2x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/24707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=24707"}],"version-history":[{"count":1,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/24707\/revisions"}],"predecessor-version":[{"id":24709,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/24707\/revisions\/24709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/24708"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=24707"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=24707"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=24707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}