{"id":25411,"date":"2023-06-05T22:16:36","date_gmt":"2023-06-05T20:16:36","guid":{"rendered":"https:\/\/www.escrimepaloise.com\/wordpress\/?p=25411"},"modified":"2023-06-22T09:07:35","modified_gmt":"2023-06-22T07:07:35","slug":"championnats-de-france-seniors-par-equipechalons-en-champagne","status":"publish","type":"post","link":"https:\/\/www.escrimepaloise.com\/wordpress\/2023\/06\/05\/championnats-de-france-seniors-par-equipechalons-en-champagne\/","title":{"rendered":"Championnats de France seniors par \u00e9quipe~Ch\u00e2lons-en-Champagne"},"content":{"rendered":"<div dir=\"ltr\">\u00a0Ce week-end avait lieu \u00e0 Chalons en Champagne les championnats de France s\u00e9niors 1\u00e8re et deuxi\u00e8me division s\u00e9niors. En l&rsquo;abscence d&rsquo;Eliott Bibi, num\u00e9ro 21 mondial, toujours bless\u00e9, notre \u00e9quipe premi\u00e8re \u00e9tait compos\u00e9e de Paco Boureau, Samuel Jarry, S\u00e9bastian Cuellar et Guilhem Jalabert. Apr\u00e8s avoir dispos\u00e9 facilement de l&rsquo;\u00e9quipe de meylan en quart de finale, nos 4 mousquetaires \u00e9chouaient en demi finale sur Clamart 45 \u00e0 37 et pour la troisi\u00e8me place sur les alsaciens de Souffel. En deuxi\u00e8me division, l&rsquo;\u00e9quipe compos\u00e9e de Mario Palacios, Fran\u00e7ois Maruelle, Tom Couderc et Nolann Miqueu, prend le meilleur sur le Cam Bordeaux pour la troisi\u00e8me place et assure ainsi un podium en terre champenoise.<\/div>\n<div dir=\"ltr\"><a href=\"https:\/\/engarde-service.com\/competition\/cechalons\/cdf-2023\/cdfshs1e\">R\u00e9sultats 1\u00e8re division<\/a><\/div>\n<div dir=\"ltr\"><a href=\"https:\/\/engarde-service.com\/competition\/cechalons\/cdf-2023\/cdfshs2e\">R\u00e9sultats 2\u00e8me division<\/a><\/div>\n<div dir=\"ltr\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0Ce week-end avait lieu \u00e0 Chalons en Champagne les championnats de France s\u00e9niors 1\u00e8re et deuxi\u00e8me division s\u00e9niors. En l&rsquo;abscence d&rsquo;Eliott Bibi, num\u00e9ro 21 mondial, toujours bless\u00e9, notre \u00e9quipe premi\u00e8re \u00e9tait compos\u00e9e de Paco Boureau, Samuel Jarry, S\u00e9bastian Cuellar et Guilhem Jalabert. Apr\u00e8s avoir dispos\u00e9 facilement de l&rsquo;\u00e9quipe de meylan en quart de finale, nos [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":25412,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-25411","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/25411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/comments?post=25411"}],"version-history":[{"count":1,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/25411\/revisions"}],"predecessor-version":[{"id":25414,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/posts\/25411\/revisions\/25414"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media\/25412"}],"wp:attachment":[{"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/media?parent=25411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/categories?post=25411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.escrimepaloise.com\/wordpress\/wp-json\/wp\/v2\/tags?post=25411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}